{"id":4970,"date":"2021-04-27T13:02:02","date_gmt":"2021-04-27T13:02:02","guid":{"rendered":"https:\/\/wissenschaftliche-integritaet.de\/?page_id=4970"},"modified":"2026-02-26T13:30:26","modified_gmt":"2026-02-26T13:30:26","slug":"news","status":"publish","type":"page","link":"https:\/\/wissenschaftliche-integritaet.de\/en\/news\/","title":{"rendered":"News"},"content":{"rendered":"\n<section class=\"main__themes \">\n    <div class=\"container-fluid\">\n\t\t            <div class=\"row\">\n                <div class=\"col-12 main__themes--heading\">\n                    <h2 >News<\/h2>\n                <\/div>\n            <\/div>\n\t\t        <div class=\"row main__themes--content\">\n        <div class=\"col-12 col-lg-4 main__themes--group\">\n            <a href=\"https:\/\/wissenschaftliche-integritaet.de\/en\/new-contribution-02-26\/\">\n\t\t\t    \t\t\t                    <h3 class=\"themes-group__heading\">New contribution February 2026<\/h3>\n                <p class=\"themes-group__text\">\n                    We are pleased to be able to provide the following new contribution that has been included in commenting, thereby expanding and enriching the portal.                    <span>More<\/span>\n                <\/p>\n            <\/a>\n        <\/div>\n\t\t        <div class=\"col-12 col-lg-4 main__themes--group\">\n            <a href=\"https:\/\/wissenschaftliche-integritaet.de\/en\/einstein-foundation-award-2026\/\">\n\t\t\t    \t\t\t                    <h3 class=\"themes-group__heading\">Einstein Foundation Award 2026<\/h3>\n                <p class=\"themes-group__text\">\n                    Together with the BIH QUEST Center for Responsible Research, the Einstein Foundation Berlin is looking for efforts and ideas aimed at fundamentally enhancing the reliability of research until April 30, 2026.                    <span>More<\/span>\n                <\/p>\n            <\/a>\n        <\/div>\n\t\t        <div class=\"col-12 col-lg-4 main__themes--group\">\n            <a href=\"https:\/\/wissenschaftliche-integritaet.de\/en\/neue-beitraege-09-25-2\/\">\n\t\t\t    \t\t\t                    <h3 class=\"themes-group__heading\">New contribution October 2025<\/h3>\n                <p class=\"themes-group__text\">\n                    We are pleased to be able to provide the following new contribution that has been included in commenting, thereby expanding and enriching the portal.                    <span>More<\/span>\n                <\/p>\n            <\/a>\n        <\/div>\n\t\t        <\/div>\n    <\/div>\n<\/section>\n\n\n\n\n\n<section class=\"main__themes background--white\">\n    <div class=\"container-fluid\">\n\t\t            <div class=\"row\">\n                <div class=\"col-12 main__themes--heading\">\n                    <h2 >Courses and workshops<\/h2>\n                <\/div>\n            <\/div>\n\t\t        <div class=\"row main__themes--content\">\n        <div class=\"col-12 col-lg-6 main__themes--group\">\n            <a href=\"https:\/\/wissenschaftliche-integritaet.de\/en\/workshop-for-ombudspersons\/\">\n\t\t\t    \t\t\t                    <h3 class=\"themes-group__heading\">Workshop: \u201cMediation and Conflict Management for Ombudspersons\u201d<\/h3>\n                <p class=\"themes-group__text\">\n                    Announcement: Workshop for Ombudspersons 2026                    <span>More<\/span>\n                <\/p>\n            <\/a>\n        <\/div>\n\t\t        <div class=\"col-12 col-lg-6 main__themes--group\">\n            <a href=\"https:\/\/wissenschaftliche-integritaet.de\/en\/courses-on-good-scientific-practice\/\">\n\t\t\t    \t\t\t                    <h3 class=\"themes-group__heading\">Courses on good scientific practice<\/h3>\n                <p class=\"themes-group__text\">\n                    Training programmes                    <span>More<\/span>\n                <\/p>\n            <\/a>\n        <\/div>\n\t\t        <\/div>\n    <\/div>\n<\/section>\n\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4970","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>News - Wissenschaftliche Integrit\u00e4t<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wissenschaftliche-integritaet.de\/en\/news\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"News - Wissenschaftliche Integrit\u00e4t\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wissenschaftliche-integritaet.de\/en\/news\/\" \/>\n<meta property=\"og:site_name\" content=\"Wissenschaftliche Integrit\u00e4t\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-26T13:30:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wissenschaftliche-integritaet.de\/wp-content\/uploads\/2020\/02\/dfg-wissenschaftliche-integritaet-defaultimage.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2324\" \/>\n\t<meta property=\"og:image:height\" content=\"1474\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wissenschaftliche-integritaet.de\\\/en\\\/news\\\/\",\"url\":\"https:\\\/\\\/wissenschaftliche-integritaet.de\\\/en\\\/news\\\/\",\"name\":\"News - Wissenschaftliche Integrit\u00e4t\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wissenschaftliche-integritaet.de\\\/en\\\/#website\"},\"datePublished\":\"2021-04-27T13:02:02+00:00\",\"dateModified\":\"2026-02-26T13:30:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wissenschaftliche-integritaet.de\\\/en\\\/news\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wissenschaftliche-integritaet.de\\\/en\\\/news\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wissenschaftliche-integritaet.de\\\/en\\\/news\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wissenschaftliche-integritaet.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wissenschaftliche-integritaet.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/wissenschaftliche-integritaet.de\\\/en\\\/\",\"name\":\"Wissenschaftliche Integrit\u00e4t\",\"description\":\"Sicherung guter wissenschaftlicher Praxis\",\"publisher\":{\"@id\":\"https:\\\/\\\/wissenschaftliche-integritaet.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wissenschaftliche-integritaet.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wissenschaftliche-integritaet.de\\\/en\\\/#organization\",\"name\":\"Deutsche Forschungsgemeinschaft e.V.\",\"url\":\"https:\\\/\\\/wissenschaftliche-integritaet.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/wissenschaftliche-integritaet.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wissenschaftliche-integritaet.de\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/GWP-Logo-v20200213@2x.png\",\"contentUrl\":\"https:\\\/\\\/wissenschaftliche-integritaet.de\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/GWP-Logo-v20200213@2x.png\",\"width\":252,\"height\":70,\"caption\":\"Deutsche Forschungsgemeinschaft e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/wissenschaftliche-integritaet.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"News - Wissenschaftliche Integrit\u00e4t","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wissenschaftliche-integritaet.de\/en\/news\/","og_locale":"en_US","og_type":"article","og_title":"News - Wissenschaftliche Integrit\u00e4t","og_url":"https:\/\/wissenschaftliche-integritaet.de\/en\/news\/","og_site_name":"Wissenschaftliche Integrit\u00e4t","article_modified_time":"2026-02-26T13:30:26+00:00","og_image":[{"width":2324,"height":1474,"url":"https:\/\/wissenschaftliche-integritaet.de\/wp-content\/uploads\/2020\/02\/dfg-wissenschaftliche-integritaet-defaultimage.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wissenschaftliche-integritaet.de\/en\/news\/","url":"https:\/\/wissenschaftliche-integritaet.de\/en\/news\/","name":"News - Wissenschaftliche Integrit\u00e4t","isPartOf":{"@id":"https:\/\/wissenschaftliche-integritaet.de\/en\/#website"},"datePublished":"2021-04-27T13:02:02+00:00","dateModified":"2026-02-26T13:30:26+00:00","breadcrumb":{"@id":"https:\/\/wissenschaftliche-integritaet.de\/en\/news\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wissenschaftliche-integritaet.de\/en\/news\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wissenschaftliche-integritaet.de\/en\/news\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wissenschaftliche-integritaet.de\/en\/"},{"@type":"ListItem","position":2,"name":"News"}]},{"@type":"WebSite","@id":"https:\/\/wissenschaftliche-integritaet.de\/en\/#website","url":"https:\/\/wissenschaftliche-integritaet.de\/en\/","name":"Wissenschaftliche Integrit\u00e4t","description":"Sicherung guter wissenschaftlicher Praxis","publisher":{"@id":"https:\/\/wissenschaftliche-integritaet.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wissenschaftliche-integritaet.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/wissenschaftliche-integritaet.de\/en\/#organization","name":"Deutsche Forschungsgemeinschaft e.V.","url":"https:\/\/wissenschaftliche-integritaet.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wissenschaftliche-integritaet.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/wissenschaftliche-integritaet.de\/wp-content\/uploads\/2020\/02\/GWP-Logo-v20200213@2x.png","contentUrl":"https:\/\/wissenschaftliche-integritaet.de\/wp-content\/uploads\/2020\/02\/GWP-Logo-v20200213@2x.png","width":252,"height":70,"caption":"Deutsche Forschungsgemeinschaft e.V."},"image":{"@id":"https:\/\/wissenschaftliche-integritaet.de\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/wissenschaftliche-integritaet.de\/en\/wp-json\/wp\/v2\/pages\/4970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wissenschaftliche-integritaet.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wissenschaftliche-integritaet.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wissenschaftliche-integritaet.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/wissenschaftliche-integritaet.de\/en\/wp-json\/wp\/v2\/comments?post=4970"}],"version-history":[{"count":42,"href":"https:\/\/wissenschaftliche-integritaet.de\/en\/wp-json\/wp\/v2\/pages\/4970\/revisions"}],"predecessor-version":[{"id":9870,"href":"https:\/\/wissenschaftliche-integritaet.de\/en\/wp-json\/wp\/v2\/pages\/4970\/revisions\/9870"}],"wp:attachment":[{"href":"https:\/\/wissenschaftliche-integritaet.de\/en\/wp-json\/wp\/v2\/media?parent=4970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}